{"id":25,"date":"2010-10-18T15:53:03","date_gmt":"2010-10-18T15:53:03","guid":{"rendered":"http:\/\/www.jukemedia.de\/blog\/?p=25"},"modified":"2017-12-03T08:21:04","modified_gmt":"2017-12-03T06:21:04","slug":"webdesigner-sind-uberflussig","status":"publish","type":"post","link":"https:\/\/www.jukemedia.de\/blog\/2010\/10\/webdesigner-sind-uberflussig\/","title":{"rendered":"Webdesigner sind \u00fcberfl\u00fcssig"},"content":{"rendered":"<p><a href=\"http:\/\/www.jukemedia.de\/blog\/wp-content\/uploads\/2010\/10\/wir-bellen-selber.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.jukemedia.de\/blog\/wp-content\/uploads\/2010\/10\/wir-bellen-selber.jpg\" alt=\"\" title=\"wir-bellen-selber\" width=\"200\" height=\"146\" class=\"alignleft size-full wp-image-89\" \/><\/a>Das sagte treffend keine Geringerer als David Ogilvy. Und heute gilt mehr denn je: In den immer enger werdenden M\u00e4rkten muss man schon sehr gut und sehr professionell bellen k\u00f6nnen, um sich gegen die Konkurrenz durchzusetzen.<\/p>\n<p>In der Praxis ist jedoch oft so, dass Webdesigner beauftragt werden, weil die Webseite m\u00f6glichst \u201esch\u00f6n\u201c sein soll &#8211; aber wer bestimmt denn eigentlich was &#8222;sch\u00f6n&#8220; ist?<\/p>\n<p>Nat\u00fcrlich ist es wichtig, dass man sich mit der eigenen Webseite gut repr\u00e4sentiert f\u00fchlt, wie jedoch w\u00e4re folgender \u00fcbrespitzter Fall zu l\u00f6sen?<\/p>\n<p>Ein 67-j\u00e4hriger Firmeninhaber ist seit Jahren erfolgreicher Hersteller von trendiger Mode f\u00fcr junge Erwachsene und hat[nbsp] Modedesigner eingestellt, die am Puls der Zeit liegen. Er selber mag es lieber edel und gediegen, L\u00f6cher in Jeanshosen sind eigentlich gar nicht sein Ding. Wie w\u00fcrde wohl die Webseite aussehen, wenn man als Sch\u00f6nheitsma\u00dfstab den Geschmack des Fabrikanten anlegen w\u00fcrde?<\/p>\n<p>Ein Webdesigner muss die Technik beherrschen &#8211; ja &#8211; aber in erster Linie muss er Phantasie und Empathie haben. Denn das was im Webdesign z\u00e4hlt ist in erster Linie seine F\u00e4higkeit sich in den Kunden bzw. dessen Zielgruppe hineinversetzen zu k\u00f6nnen. Er muss eine passende Idee finden k\u00f6nnen und diese Idee in das Medium Webseite umsetzen. Es mag wichtig sein, dass ein Webdesigner auch ein gutes Gef\u00fchl f\u00fcr Formen und Farben haben sollte, aber sein pers\u00f6nlicher Geschmack hat bei der Arbeit f\u00fcr einen Kunden so wenig zu suchen wie Fische Fahrr\u00e4der brauchen.<\/p>\n<p>Soweit bekomme ich bestimmt nickende Zustimmung von Auftraggebern.<\/p>\n<p>Meine ketzerische Frage ist jedoch: Wie steht es denn bei Ihnen mit der Empathie f\u00fcr Ihre Zielgruppe?<br \/>\nK\u00f6nnen Sie gut zwischen Ihrem eigenen Geschmack und dem, was Ihre Zielgruppe braucht, unterscheiden?<br \/>\nWozu brauchen Sie einen Webdesigner? ;-)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn da nur nicht diese dumme Technik w\u00e4re. Alles andere kann ich sowieso selber. &#8211; Wirklich?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[14,18,32],"yst_prominent_words":[],"class_list":["post-25","post","type-post","status-publish","format-standard","hentry","category-webdesign","tag-webdesign-2","tag-webseite","tag-gestaltung"],"_links":{"self":[{"href":"https:\/\/www.jukemedia.de\/blog\/wp-json\/wp\/v2\/posts\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jukemedia.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jukemedia.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jukemedia.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jukemedia.de\/blog\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":3,"href":"https:\/\/www.jukemedia.de\/blog\/wp-json\/wp\/v2\/posts\/25\/revisions"}],"predecessor-version":[{"id":213,"href":"https:\/\/www.jukemedia.de\/blog\/wp-json\/wp\/v2\/posts\/25\/revisions\/213"}],"wp:attachment":[{"href":"https:\/\/www.jukemedia.de\/blog\/wp-json\/wp\/v2\/media?parent=25"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jukemedia.de\/blog\/wp-json\/wp\/v2\/categories?post=25"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jukemedia.de\/blog\/wp-json\/wp\/v2\/tags?post=25"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.jukemedia.de\/blog\/wp-json\/wp\/v2\/yst_prominent_words?post=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}